{"id":4214,"date":"2024-02-08T10:14:43","date_gmt":"2024-02-08T10:14:43","guid":{"rendered":"https:\/\/www.zonwizard.com\/blog\/?p=4214"},"modified":"2024-02-08T10:14:43","modified_gmt":"2024-02-08T10:14:43","slug":"come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei","status":"publish","type":"post","link":"https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/","title":{"rendered":"Come vendere su Amazon USA: La Guida Completa per seller europei"},"content":{"rendered":"<p>Capita spesso che numerosi Seller Europei confrontandosi con il nostro supporto mostrino timori nel muovere i primi passi per espandere le proprie vendite su Amazon in Nord America, mercato ricco e difficile, lontano, ma troppo ghiotto per non provarci.<\/p>\n<p>Se sei interessato a conoscere quali sono i 6 requisiti iniziali per <strong>valutare l\u2019ingresso nel mercato Amazon<\/strong> con pi\u00f9 alte vendite, allora questo articolo fa per te.<!--more--><\/p>\n<p>In ZonWizard supportiamo anche il mercato Nord Americano e possiamo aiutare il seller Amazon nella massimizzazione dei profitti e nella gestione fiscale anche per le vendite fatte sui marketplace, amazon.com amazon.ca, amazon.com.mx<\/p>\n\t\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\t\tvar gCaptchaSibWidget;\n                        var onloadSibCallbackInvisible = function () {\n\n                            var element = document.getElementsByClassName('sib-default-btn');\n                            var countInvisible = 0;\n                            var indexArray = [];\n                            jQuery('.sib-default-btn').each(function (index, el) {\n                                if ((jQuery(el).attr('id') == \"invisible\")) {\n                                    indexArray[countInvisible] = index;\n                                    countInvisible++\n                                }\n                            });\n\n                            jQuery('.invi-recaptcha').each(function (index, el) {\n                                grecaptcha.render(element[indexArray[index]], {\n                                    'sitekey': jQuery(el).attr('data-sitekey'),\n                                    'callback': sibVerifyCallback,\n                                });\n                            });\n                        };\n\t\t\t\t\t<\/script>\n\t\t\t\t\t                <script src=\"https:\/\/www.google.com\/recaptcha\/api.js?onload=onloadSibCallbackInvisible&render=explicit\" async defer><\/script>\n\t\t\t\t\n\t\t\t<form id=\"sib_signup_form_3\" method=\"post\" class=\"sib_signup_form\">\n\t\t\t\t<div class=\"sib_loader\" style=\"display:none;\"><img data-recalc-dims=\"1\"\n\t\t\t\t\t\t\tsrc=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-includes\/images\/spinner.gif?w=650&#038;ssl=1\" alt=\"loader\"><\/div>\n\t\t\t\t<input type=\"hidden\" name=\"sib_form_action\" value=\"subscribe_form_submit\">\n\t\t\t\t<input type=\"hidden\" name=\"sib_form_id\" value=\"3\">\n                <input type=\"hidden\" name=\"sib_form_alert_notice\" value=\"Please fill out this field\">\n                <input type=\"hidden\" name=\"sib_form_invalid_email_notice\" value=\"Your email address is invalid\">\n                <input type=\"hidden\" name=\"sib_security\" value=\"479c0a34c2\">\n\t\t\t\t<div class=\"sib_signup_box_inside_3\">\n\t\t\t\t\t<div style=\"\/*display:none*\/\" class=\"sib_msg_disp\">\n\t\t\t\t\t<\/div>\n                                            <div id=\"sib_captcha_invisible\" class=\"invi-recaptcha\" data-sitekey=\"6LcMN7gUAAAAAD-_qJb0nFTTZqsPjxY-UjJ2aAoa\"><\/div>\n                    \t\t\t\t\t<div class=\"form-container\">\r\n        <h3 class=\"form-title\"><strong>Iscriviti alla Newsletter<\/strong><\/h3>\r\n        <p>Articoli, mini-guide e aggiornamenti sul mondo Amazon dagli esperti del settore.<\/p>\r\n        <div>\r\n            <div class=\"form-input\">\r\n                <input type=\"text\" class=\"sib-NOME-area\" name=\"NOME\" placeholder=\"Nome\" required=\"required\">\r\n            <\/div>\r\n            <div class=\"form-input\">\r\n                <input type=\"email\" class=\"sib-email-area\" name=\"email\" placeholder=\"Email\" required=\"required\">\r\n            <\/div>\r\n            <div class=\"checkbox-alignment\">\r\n                <input type=\"checkbox\" name=\"terms\" required=\"required\"> Accetto la <a class=\"text-white\" href=\"https:\/\/www.zonwizard.com\/it\/privacy\"><u> privacy policy<\/u><\/a>\r\n\r\n            <\/div>\r\n        <\/div>\r\n\r\n        <input type=\"text\" class=\"sib-LANGUAGE-area\" name=\"LANGUAGE\" value=\"it\">\r\n\r\n\r\n        <input type=\"submit\" id=\"invisible\" class=\"sib-default-btn\" value=\"Iscriviti alla Newsletter\">\r\n    <\/div>\t\t\t\t<\/div>\n\t\t\t<\/form>\n\t\t\t<style>\n\t\t\t\tform#sib_signup_form_3 {background-color: #727cf5;padding: 30px;border-radius: 30px;margin: auto; -moz-box-sizing:border-box; -webkit-box-sizing: border-box; box-sizing: border-box; color:white; margin-bottom:20px } form#sib_signup_form_3 input[type=text],form#sib_signup_form_3 input[type=email], form#sib_signup_form_3 select { width: 100%; border: 1px solid #bbb; height: auto; margin: 5px 0 0 0; background-color:#e7e9fd;} form#sib_signup_form_3 .sib-default-btn { width:100%; margin: 5px 0; padding: 10px 12px; color:#727cf5; background-color: #fff; border: 2px solid #fff; font-size: 14px; font-weight:400; line-height: 1.4285; text-align: center; cursor: pointer; vertical-align: middle; -webkit-user-select:none; -moz-user-select:none; -ms-user-select:none; user-select:none; white-space: normal; border-radius: 500px; } form#sib_signup_form_3 .sib-default-btn:hover { background-color: #727cf5;color: #fff;border: 2px solid #fff;} form#sib_signup_form_3 p{ margin: 10px 0 0 0; } form#sib_signup_form_3 .sib-LANGUAGE-area{ display: none; } .form-input { width: 47%; margin-bottom: 10px; display:inline-block; } .text-white{color:white} .form-container { max-width: 400px; margin: auto; color: white; text-align: center } .form-title { margin-bottom: 0px; margin-top: 0px }form#sib_signup_form_3 p.sib-alert-message {\n    padding: 6px 12px;\n    margin-bottom: 20px;\n    border: 1px solid transparent;\n    border-radius: 4px;\n    -webkit-box-sizing: border-box;\n    -moz-box-sizing: border-box;\n    box-sizing: border-box;\n}\nform#sib_signup_form_3 p.sib-alert-message-error {\n    background-color: #f2dede;\n    border-color: #ebccd1;\n    color: #a94442;\n}\nform#sib_signup_form_3 p.sib-alert-message-success {\n    background-color: #dff0d8;\n    border-color: #d6e9c6;\n    color: #3c763d;\n}\nform#sib_signup_form_3 p.sib-alert-message-warning {\n    background-color: #fcf8e3;\n    border-color: #faebcc;\n    color: #8a6d3b;\n}\n\t\t\t<\/style>\n\t\t\t\n<p>&nbsp;<\/p>\n<h2>Quali sono i requisiti fiscali per poter vendere in Amazon Nord America?<\/h2>\n<h3><\/h3>\n<h3>1. EIN &#8211; employer identification number &#8211;<\/h3>\n<p>La prima cosa di cui dovremmo occuparci per vendere in NordAmerica \u00e8 ottenere L\u2019EIN, si tratta di un <strong>numero di identificazione fiscale federale per le imprese<\/strong>, rilasciato dall\u2019IRS. L\u2019IRS (Internal Revenue Service) \u00e8 l\u2019agenzia delle entrate Americane ed \u00e8 l\u2019autorit\u00e0 fiscale nazionale degli Stati Uniti che rilascia questo codice di 9 cifre.<\/p>\n<p>In generale, devi richiedere l\u2019EIN se hai dipendenti, operi come societ\u00e0, o se devi presentare dichiarazioni fiscali specifiche.<br \/>\nQuindi se sei un venditore ecommerce internazionale che vuole vendere su piattaforme online negli Stati Uniti, <strong>devi ottenere un EIN per soddisfare i requisiti fiscali<\/strong>.<br \/>\nInoltre questo codice \u00e8 indispensabile per l\u2019importazione e lo sdoganamento delle tue merci negli Stati Uniti.<\/p>\n<p>Per ottenere un EIN, \u00e8 possibile compilare il modulo SS-4 (Application for Employer Identification Number) fornito dall&#8217;IRS e inviarlo tramite posta, fax, online o telefonando direttamente.<br \/>\nPer registrare l\u2019EIN <strong>occorrono dalle 2 alle 4 settimane<\/strong> e per avere maggiori informazioni puoi visitare e seguire le indicazioni dell\u2019IRS a questo link: <a href=\"https:\/\/www.irs.gov\/businesses\/small-businesses-self-employed\/how-to-apply-for-an-ein\">https:\/\/www.irs.gov\/businesses\/small-businesses-self-employed\/how-to-apply-for-an-ein<\/a><br \/>\nIn alternativa, puoi farti assistere dal tuo consulente fiscale internazionale per compiere l\u2019intera registrazione.<\/p>\n<p><span class=\"colour\"><span class=\"x_-1164479834size\"><span class=\"font\"><span class=\"size\"><a href=\"https:\/\/www.zonwizard.com\/it\/features?utm_source=blog&amp;utm_medium=banner&amp;utm_campaign=Scopri_Fisco#accounting\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2138 size-large\" title=\"Semplifica la contabilit\u00e0 della vendita su Amazon con ZonWizard\" src=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/02\/Banner-Tool-Fisco-ZW-Ita.png?resize=650%2C159&#038;ssl=1\" alt=\"Con ZonWizard automatizzi i report fiscali sulla vendita su Amazon da comunicare al tuo commercialista. Registro dei corrispettivi, dichiarazioni IVA e OSS in un click.\" width=\"650\" height=\"159\" srcset=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/02\/Banner-Tool-Fisco-ZW-Ita.png?resize=1024%2C250&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/02\/Banner-Tool-Fisco-ZW-Ita.png?resize=810%2C198&amp;ssl=1 810w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/02\/Banner-Tool-Fisco-ZW-Ita.png?resize=1140%2C278&amp;ssl=1 1140w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/02\/Banner-Tool-Fisco-ZW-Ita.png?resize=700%2C171&amp;ssl=1 700w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/02\/Banner-Tool-Fisco-ZW-Ita.png?resize=300%2C73&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/02\/Banner-Tool-Fisco-ZW-Ita.png?resize=768%2C187&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/02\/Banner-Tool-Fisco-ZW-Ita.png?resize=1536%2C375&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/02\/Banner-Tool-Fisco-ZW-Ita.png?resize=1200%2C293&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/02\/Banner-Tool-Fisco-ZW-Ita.png?w=1640&amp;ssl=1 1640w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/02\/Banner-Tool-Fisco-ZW-Ita.png?w=1300&amp;ssl=1 1300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/a><\/span><\/span><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<h3>2. Nexus<\/h3>\n<p>Il \u201cnexus\u201d <strong>\u00e8 il \u201cnesso\u201d, il legame significativo con uno stato americano <\/strong>che obbliga l\u2019azienda a riscuotere e versare la \u201csales tax\u201d (tassa sulle vendite) in quello stesso stato.<\/p>\n<p>Ci sono tre categorie di Nexus: fisico, economico o marketplace ed <strong>ogni stato decide quali tipologie di nexus applicare<\/strong> e quali sono i fattori ne determinano l\u2019attuazione.<\/p>\n<h4>2.1 Nexus economico:<\/h4>\n<p>Questo tipo di Nexus prende in considerazione le s<strong>oglie di vendita economiche<\/strong> o un certo numero di <strong>transazioni<\/strong>, per valutare il collegamento sostanziale tra l&#8217;azienda e lo Stato.<br \/>\nNegli anni quasi tutti gli Stati si sono uniformati alla soglia di vendite annue pari a 100.000$, ma non mancano le eccezioni.<\/p>\n<p>Ad esempio in Texas le vendite annue senza avere obbligo di registrare la sales tax sono pari a 500,000$. Oppure per le Hawaii la soglia \u00e8 fissata a $100,000 di vendite annue nello stato e 200 transazioni.<br \/>\nIn questo caso quando superi uno dei due parametri avrai l\u2019obbligo di andare a registrare la sales tax in quello stato.<\/p>\n<h4>2.2 Nexus fisico:<\/h4>\n<p>in questo tipo di nexus non interessano le soglie di fatturato o transazioni, ma interessa solamente se viene <strong>stoccata la merce o se si \u00e8 presenti<\/strong> fisicamente con magazzino, ufficio ecc\u2026<br \/>\nAd esempio se stocco la merce in uno stato che applica il Nexus fisico devo registrarmi per la sales tax.<\/p>\n<h4>2.3 Nexus Marketplace:<\/h4>\n<p>Questo tipo di nexus si verifica quando si effettuano <strong>vendite tramite un marketplace<\/strong> (come Amazon o ebay). Negli stati che applicano questo nexus la responsabilit\u00e0 di collezionare e versare la sales Tax viene attribuita al marketplace anzich\u00e9 al venditore.<\/p>\n<p>&nbsp;<\/p>\n<h3>3. Sales tax<\/h3>\n<p>Se abbiamo un nexus in un determinato stato, per le vendite spedite verso questo stato dovremmo applicare e versare la Sales Tax.<\/p>\n<div class=\"box info\"><div class=\"boxInside\"><i class=\"fa fa-info-circle boxIconStyle\"><\/i> \u201cIn amazon.com il <strong>prezzo esposto<\/strong> negli annunci \u00e8 <strong>sempre netto<\/strong> e la Sales Tax viene calcolata ed applicata al momento del pagamento, in base allo Stato e citt\u00e0 in cui il prodotto \u00e8 stato acquistato.\u201d <\/div><\/div>\n<p><strong>La Sales Tax \u00e8 l&#8217;equivalente dell\u2019IVA Europea<\/strong>, ma questa tassa sulle vendite varia oltre che a livello statale anche a livello locale. Quindi per 50 stati potremmo avere 50 aliquote e 50 legislazioni diverse, oltre alle particolarit\u00e0 che potrebbero essere aggiunte dalle autorit\u00e0 locali.<br \/>\nFortunatamente per i seller Amazon in molti stati \u00e8 stata introdotta la <strong>Marketplace Facilitator Legislation<\/strong>.<\/p>\n<blockquote>\n<p style=\"text-align: right;\"><em>\u201cLa legislazione sui Marketplace Facilitator \u00e8 un insieme di leggi che spostano gli obblighi di raccolta e versamento dell&#8217;imposta sulle vendite da un venditore terzo al marketplace facilitator. Come marketplace facilitator, Amazon sar\u00e0 ora responsabile di calcolare, riscuotere, versare e rimborsare l&#8217;imposta sulle vendite statali sulle vendite effettuate da venditori terzi per transazioni destinate agli stati in cui \u00e8 stata promulgata la legislazione sulla raccolta tramite Marketplace Facilitator. In certi stati, le tasse locali non sono incluse nella Legislazione sui Marketplace Facilitator; Amazon non \u00e8 responsabile di quelle tasse.\u201d<\/em><\/p>\n<\/blockquote>\n<p>In sostanza, invece di raccogliere la sales tax dalle vendite effettuate ai clienti nello stato in cui \u00e8 presente il nexus marketplace, <strong>Amazon calcola in automatico la sales tax in base alla localit\u00e0 di spedizione e la trattiene al tuo posto<\/strong>.<\/p>\n<p>A questo link puoi verificare per quali stati americani Amazon applica il marketplace facilitator <a href=\"https:\/\/www.amazon.com\/gp\/help\/customer\/display.html?nodeId=202211260\">https:\/\/www.amazon.com\/gp\/help\/customer\/display.html?nodeId=202211260<\/a><\/p>\n<p>Nonostante questa facilitazione, <strong>restano alcune casistiche che non vengono coperte dal marketplace facilitator<\/strong> per cui pu\u00f2 essere necessario ottenere un Sales Tax Permit ed effettuare autonomamente le dichiarazioni fiscali in alcuni stati.<\/p>\n<p>Ad esempio alcuni stati americani potrebbero seguire la legislazione del nexus fisico e se spedisci in FBA, Amazon pu\u00f2 spostare i tuoi prodotti in un centro logistico, rendendo necessaria la registrazione della sales tax in quello stato (anche se sar\u00e0 il marketplace a collezionare e versare la sales tax).<\/p>\n<p>Altra particolarit\u00e0 \u00e8 che non tutti gli stati aderiscono alla Marketplace facilitator legislation ed \u00e8 responsabilit\u00e0 diretta del venditore fare la dichiarazione, senza l\u2019intermediazione del marketplace. Dovrai quindi avere un sales tax Permit, collezionare e versare la sales tax nello stato in questione.<\/p>\n<p>Date le molte casistiche da tenere in considerazione, ti consigliamo di farti seguire da un consulente fiscale esperto che potr\u00e0 assisterti nella regolarizzazione della tua posizione e negli adempimenti richiesti per il tuo caso specifico.<\/p>\n<p>&nbsp;<\/p>\n<h3>4. Indirizzo Fisico<\/h3>\n<p>Una volta che avrai ottenuto l\u2019EIN ed i sales tax permit in base ai criteri definiti sopra, dovrai dotarti di un indirizzo fisico dove ricevere delle <strong>comunicazioni immediate da parte dell\u2019IRS<\/strong>. Questo ente invia lettere anche oltre oceano, ma dato che la scadenza del pagamento \u00e8 entro 2 o 3 settimane dalla spedizione della raccomandata, non \u00e8 detto che la posta sia altrettanto celere ad arrivare.<br \/>\nSe ti avvali di consulenti fiscali internazionali (guarda i nostri bonus qui) questo indirizzo ti verr\u00e0 fornito dagli stessi consulenti, che faranno da rappresentante fiscale e tu potrai avere il tuo indirizzo dove ricevere la posta, senza ritardi.<\/p>\n<p>&nbsp;<\/p>\n<h3>5. Permessi di vendita e importazioni dei prodotti<\/h3>\n<p>Prima di importare la tua merce negli stati uniti, \u00e8 fondamentale conoscere se i prodotti che andrai a vendere sono <strong>soggetti a restrizioni<\/strong> o <strong>certificazioni specifiche<\/strong> per il mercato statunitense.<br \/>\nIn particolare se parliamo di cibo, integratori, occhiali da sole o tutto ci\u00f2 che pu\u00f2 essere ingerito o indossato da persone ed animali, questi prodotti sono soggetti all\u2019iscrizione all\u2019<strong>FDA (Food and Drug Administration)<\/strong> che \u00e8 l&#8217;ente governativo statunitense che si occupa della regolamentazione dei prodotti alimentari e farmaceutici.<br \/>\nAnche in questo caso sar\u00e0 necessario avvalersi di consulenza specializzata per conoscere i requisiti dei prodotti ed ottenere le certificazioni necessarie prima dell\u2019importazione.<\/p>\n<div class=\"box info\"><div class=\"boxInside\"><i class=\"fa fa-info-circle boxIconStyle\"><\/i> <strong>Tip. No dazi sotto gli 800$ per i vostri micro-test di mercato USA.<\/strong><br \/>\nQuando le spedizioni entrano negli Stati Uniti e sono valutate come di valore inferiore a 800 dollari, vengono considerate come &#8220;merci di basso valore&#8221; e sono esenti dal pagamento dei dazi doganali.<\/p>\n<p>Questa politica \u00e8 conosciuta come &#8220;<strong>de minimis threshold<\/strong>&#8221; ed \u00e8 stata istituita per semplificare le spedizioni internazionali di piccoli beni e ridurre la burocrazia associata al processo doganale per importazioni di valore relativamente basso.<br \/>\nIn sostanza per le spedizioni verso gli Stati Uniti non si applicano dazi per merce con valore inferiore agli 800 dollari. Verificando i dazi al momento dell\u2019importazione potrai fare dei micro-test di mercato evitando di pagare i dazi doganali.<\/p>\n<p>\u00c8 importante tenere presente che questa esenzione dai dazi<strong> non si applica a tutti i tipi di merci<\/strong> e che possono esserci eccezioni o restrizioni specifiche per determinati articoli. Pertanto, \u00e8 consigliabile verificare con il vostro consulente fiscale (vedi Avask) le politiche doganali e le eventuali tasse aggiuntive prima di effettuare spedizioni internazionali verso gli Stati Uniti.<\/div><\/div>\n<p>&nbsp;<\/p>\n<h3>6. Cos&#8217;altro devi sapere per vendere su Amazon NordAmerica?<\/h3>\n<h3><\/h3>\n<h4>6.1 Programma NAF<\/h4>\n<p>Attraverso il programma NAF <strong>&#8220;North America Unified Account&#8221; di Amazon<\/strong>, i venditori possono utilizzare l&#8217;infrastruttura di Amazon negli Stati Uniti per immagazzinare la merce e beneficiare di Amazon FBA (Fulfillment by Amazon) per la gestione della logistica e l&#8217;adempimento degli ordini. Ci\u00f2 consente di vendere sui marketplace di Amazon in <strong>Canada e Messico<\/strong> senza la necessit\u00e0 di aprire posizioni fiscali o magazzini in quei paesi.<\/p>\n<p>Ottimo per verificare se c\u2019\u00e8 richiesta del nostro prodotto nella fase iniziale di vendita su questi due paesi. Poi in base al volume degli ordini potrai valutare se aprire delle posizioni fiscali anche in questi paesi e stoccare i prodotti localmente.<\/p>\n<h3><\/h3>\n<h4>6.2 Modulo 1099-K<\/h4>\n<p>All\u2019inizio di ogni nuovo anno Amazon fornisce all\u2019IRS e al venditore il modulo 1099-K che <strong>riepiloga tutte le vendite effettuate nell\u2019anno<\/strong> <strong>precedente<\/strong> dal 1\u00b0 Gennaio al 31 Dicembre negli Stati Uniti. Vengono riportate le entrate provenienti da pagamenti tramite carte di credito e servizi di pagamento terzi.<br \/>\nAmazon emette il modulo 1099-K per i venditori che superano determinati volumi di transazioni e guadagni attraverso la piattaforma. Nel 2022 si dovevano superare le 200 transazioni o fare vendite superiori a $20.000. Dal 2023 invece tutte le attivit\u00e0 che superano i 600$ di fatturato nell\u2019anno solare devono compilare il modulo per segnalare all&#8217;IRS le entrate generate su Amazon.<\/p>\n<div class=\"box info\"><div class=\"boxInside\"><i class=\"fa fa-info-circle boxIconStyle\"><\/i> \u201cAmazon mette a disposizione del venditore il modulo 1099-K nella pagina \u201cRaccolta di documenti fiscali\u201d del seller central.\u201d <\/div><\/div>\nQuesto modulo potr\u00e0 essere fornito al tuo consulente fiscale per certificare i redditi ottenuti dalle vendite negli Stati Uniti.<\/p>\n<h3><\/h3>\n<h4>6.3 Modulo W-8BEN-E<\/h4>\n<p>Questo modulo dell&#8217;IRS \u00e8 una autocertificazione che attesta che l&#8217;azienda non \u00e8 residente fiscale negli Stati Uniti d&#8217;America. \u00c8 importante compilarlo correttamente perch\u00e9 permette di non essere soggetto alla ritenuta d&#8217;acconto del 30% sui pagamenti ricevuti da committenti americani. Questo in virt\u00f9 degli accordi bilaterali tra paesi europei e Stati Uniti contro la doppia imposizione.<br \/>\nPertanto, se un Amazon seller europeo opera negli Stati Uniti e vuole beneficiare di tali agevolazioni fiscali, dovr\u00e0 compilare questo modulo e fornirlo ad Amazon.<\/p>\n<p>&nbsp;<\/p>\n<h2>Vendere su Amazon USA: Conclusioni<\/h2>\n<p>Hai appena scoperto i passaggi fondamentali per avviare con successo le tue vendite su Amazon Nord America! Grazie a questo articolo, ora hai la conoscenza necessaria per navigare nel complesso mondo della fiscalit\u00e0 e delle normative statunitensi.<\/p>\n<p>Leggendo fin qua, hai imparato come ottenere l&#8217;EIN, come gestire il Nexus e la Sales Tax in modo efficiente, come garantire un indirizzo fisico affidabile e come affrontare le sfide legate alle certificazioni dei prodotti. Inoltre, hai scoperto che potrai sfruttare il programma NAF di Amazon per vendere in Messico e Canada senza ulteriori complicazioni e quali documenti presentare per effettuare la tua dichiarazione delle vendite in USA: il modulo 1099-K e il W-8BEN-E.<\/p>\n<p>Ora la paura dell&#8217;ignoto non ti trattiene pi\u00f9 dal conquistare nuovi mercati e potrai sfruttare al massimo le potenzialit\u00e0 del mercato pi\u00f9 ricco di Amazon.<\/p>\n<p>Contattaci alla email <em><strong>supporto@ zonwizard.com<\/strong><\/em> se hai dubbi su come procedere o se desideri il nostro supporto per avviare questa nuova avventura.<\/p>\n<p>Il team di ZonWizard \u00e8 qui per facilitare l\u2019espansione del tuo business anche su Amazon Nord America, grazie alla nostra suite di servizi innovativi e ai nostri partner internazionali!<\/p>\n<p><span class=\"colour\"><span class=\"x_-1164479834size\"><span class=\"font\"><span class=\"size\"><div class=\"cta-container\">\r\n<h3 class=\"cta-h2\"><strong>Prova il Tool Fisco Gratis<\/strong><\/h3>\r\n<p class=\"\">Compiler\u00e0 in automatico il registro dei corrispettivi, le dichiarazioni IVA e OSS e molto molto altro. Se non conosci ancora il Tool Fisco di ZonWizard puoi iniziare la tua prova gratuita di 14 giorni cliccando sul bottone sotto<\/p>\r\n<p class=\"\"><a class=\"button cta-button\" href=\"https:\/\/www.zonwizard.com\/it\/features?utm_source=blog&amp;utm_medium=cta_pulsante_Fisco&amp;utm_campaign=Prova+il+Tool+Fisco+Gratis#accounting\">Scopri di pi\u00f9<\/a><\/p>\r\n\r\n<\/div><\/span><\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Capita spesso che numerosi Seller Europei confrontandosi con il nostro supporto mostrino timori nel muovere i primi passi per espandere le proprie vendite su Amazon in Nord America, mercato ricco e difficile, lontano, ma troppo ghiotto per non provarci. Se sei interessato a conoscere quali sono i 6 requisiti iniziali per valutare l\u2019ingresso nel mercato&hellip;<\/p>\n","protected":false},"author":179014711,"featured_media":4265,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_crdt_document":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[34,50],"tags":[],"class_list":["post-4214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accounting","category-profit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come vendere su Amazon USA: La Guida Completa per seller europei - ZonWizard<\/title>\n<meta name=\"description\" content=\"Sei interessato a capire come vendere su Amazon Nordamerica? quali sono gli step iniziali che devi sapere? Leggi la guida definitiva ZonWizard per valutare l&#039;espansione del tuo business oltreoceano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come vendere su Amazon USA: La Guida Completa per seller europei - ZonWizard\" \/>\n<meta property=\"og:description\" content=\"Sei interessato a capire come vendere su Amazon Nordamerica? quali sono gli step iniziali che devi sapere? Leggi la guida definitiva ZonWizard per valutare l&#039;espansione del tuo business oltreoceano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/\" \/>\n<meta property=\"og:site_name\" content=\"ZonWizard\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-08T10:14:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zonwizard.com\/blog\/wp-content\/uploads\/2024\/02\/AdobeStock_226574010-scaled-e1707380680278.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2402\" \/>\n\t<meta property=\"og:image:height\" content=\"908\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mirkocalamante\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"mirkocalamante\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/it\\\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/it\\\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\\\/\"},\"author\":{\"name\":\"mirkocalamante\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#\\\/schema\\\/person\\\/814cc3af272d7dfc29d35d2323e68b8d\"},\"headline\":\"Come vendere su Amazon USA: La Guida Completa per seller europei\",\"datePublished\":\"2024-02-08T10:14:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/it\\\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\\\/\"},\"wordCount\":1952,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/it\\\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.zonwizard.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/AdobeStock_226574010-scaled-e1707380680278.jpeg?fit=2402%2C908&ssl=1\",\"articleSection\":[\"Fisco\",\"Profitto\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/it\\\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/it\\\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\\\/\",\"url\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/it\\\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\\\/\",\"name\":\"Come vendere su Amazon USA: La Guida Completa per seller europei - ZonWizard\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/it\\\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/it\\\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.zonwizard.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/AdobeStock_226574010-scaled-e1707380680278.jpeg?fit=2402%2C908&ssl=1\",\"datePublished\":\"2024-02-08T10:14:43+00:00\",\"description\":\"Sei interessato a capire come vendere su Amazon Nordamerica? quali sono gli step iniziali che devi sapere? Leggi la guida definitiva ZonWizard per valutare l'espansione del tuo business oltreoceano.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/it\\\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/it\\\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/it\\\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.zonwizard.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/AdobeStock_226574010-scaled-e1707380680278.jpeg?fit=2402%2C908&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.zonwizard.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/AdobeStock_226574010-scaled-e1707380680278.jpeg?fit=2402%2C908&ssl=1\",\"width\":2402,\"height\":908,\"caption\":\"Closeup of rippled American flag\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/it\\\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come vendere su Amazon USA: La Guida Completa per seller europei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/\",\"name\":\"ZonWizard\",\"description\":\"Academy\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#organization\",\"name\":\"ZonWizard\",\"url\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.zonwizard.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/ZW_logo_L2TCB-1.png?fit=1400%2C248&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.zonwizard.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/ZW_logo_L2TCB-1.png?fit=1400%2C248&ssl=1\",\"width\":1400,\"height\":248,\"caption\":\"ZonWizard\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCvVlC0KBpllkAWBl63VPeBA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#\\\/schema\\\/person\\\/814cc3af272d7dfc29d35d2323e68b8d\",\"name\":\"mirkocalamante\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c53f576c4b659945da179d0a0b30542cc60b602a5bf15a9d033e0cf0e9b0ee8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c53f576c4b659945da179d0a0b30542cc60b602a5bf15a9d033e0cf0e9b0ee8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c53f576c4b659945da179d0a0b30542cc60b602a5bf15a9d033e0cf0e9b0ee8?s=96&d=mm&r=g\",\"caption\":\"mirkocalamante\"},\"url\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/author\\\/mirkocalamante\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come vendere su Amazon USA: La Guida Completa per seller europei - ZonWizard","description":"Sei interessato a capire come vendere su Amazon Nordamerica? quali sono gli step iniziali che devi sapere? Leggi la guida definitiva ZonWizard per valutare l'espansione del tuo business oltreoceano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/","og_locale":"en_US","og_type":"article","og_title":"Come vendere su Amazon USA: La Guida Completa per seller europei - ZonWizard","og_description":"Sei interessato a capire come vendere su Amazon Nordamerica? quali sono gli step iniziali che devi sapere? Leggi la guida definitiva ZonWizard per valutare l'espansione del tuo business oltreoceano.","og_url":"https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/","og_site_name":"ZonWizard","article_publisher":"https:\/\/www.facebook.com\/","article_published_time":"2024-02-08T10:14:43+00:00","og_image":[{"width":2402,"height":908,"url":"https:\/\/www.zonwizard.com\/blog\/wp-content\/uploads\/2024\/02\/AdobeStock_226574010-scaled-e1707380680278.jpeg","type":"image\/jpeg"}],"author":"mirkocalamante","twitter_card":"summary_large_image","twitter_misc":{"Written by":"mirkocalamante","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/#article","isPartOf":{"@id":"https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/"},"author":{"name":"mirkocalamante","@id":"https:\/\/www.zonwizard.com\/blog\/#\/schema\/person\/814cc3af272d7dfc29d35d2323e68b8d"},"headline":"Come vendere su Amazon USA: La Guida Completa per seller europei","datePublished":"2024-02-08T10:14:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/"},"wordCount":1952,"commentCount":0,"publisher":{"@id":"https:\/\/www.zonwizard.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2024\/02\/AdobeStock_226574010-scaled-e1707380680278.jpeg?fit=2402%2C908&ssl=1","articleSection":["Fisco","Profitto"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/","url":"https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/","name":"Come vendere su Amazon USA: La Guida Completa per seller europei - ZonWizard","isPartOf":{"@id":"https:\/\/www.zonwizard.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/#primaryimage"},"image":{"@id":"https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2024\/02\/AdobeStock_226574010-scaled-e1707380680278.jpeg?fit=2402%2C908&ssl=1","datePublished":"2024-02-08T10:14:43+00:00","description":"Sei interessato a capire come vendere su Amazon Nordamerica? quali sono gli step iniziali che devi sapere? Leggi la guida definitiva ZonWizard per valutare l'espansione del tuo business oltreoceano.","breadcrumb":{"@id":"https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/#primaryimage","url":"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2024\/02\/AdobeStock_226574010-scaled-e1707380680278.jpeg?fit=2402%2C908&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2024\/02\/AdobeStock_226574010-scaled-e1707380680278.jpeg?fit=2402%2C908&ssl=1","width":2402,"height":908,"caption":"Closeup of rippled American flag"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zonwizard.com\/blog\/it\/come-vendere-su-amazon-usa-la-guida-completa-per-seller-europei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zonwizard.com\/blog\/it\/"},{"@type":"ListItem","position":2,"name":"Come vendere su Amazon USA: La Guida Completa per seller europei"}]},{"@type":"WebSite","@id":"https:\/\/www.zonwizard.com\/blog\/#website","url":"https:\/\/www.zonwizard.com\/blog\/","name":"ZonWizard","description":"Academy","publisher":{"@id":"https:\/\/www.zonwizard.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zonwizard.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.zonwizard.com\/blog\/#organization","name":"ZonWizard","url":"https:\/\/www.zonwizard.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zonwizard.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2021\/09\/ZW_logo_L2TCB-1.png?fit=1400%2C248&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2021\/09\/ZW_logo_L2TCB-1.png?fit=1400%2C248&ssl=1","width":1400,"height":248,"caption":"ZonWizard"},"image":{"@id":"https:\/\/www.zonwizard.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/www.youtube.com\/channel\/UCvVlC0KBpllkAWBl63VPeBA"]},{"@type":"Person","@id":"https:\/\/www.zonwizard.com\/blog\/#\/schema\/person\/814cc3af272d7dfc29d35d2323e68b8d","name":"mirkocalamante","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6c53f576c4b659945da179d0a0b30542cc60b602a5bf15a9d033e0cf0e9b0ee8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c53f576c4b659945da179d0a0b30542cc60b602a5bf15a9d033e0cf0e9b0ee8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c53f576c4b659945da179d0a0b30542cc60b602a5bf15a9d033e0cf0e9b0ee8?s=96&d=mm&r=g","caption":"mirkocalamante"},"url":"https:\/\/www.zonwizard.com\/blog\/author\/mirkocalamante\/"}]}},"lang":"it","translations":{"it":4214,"en":4250,"es":4348,"fr":4742,"de":4744},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2024\/02\/AdobeStock_226574010-scaled-e1707380680278.jpeg?fit=2402%2C908&ssl=1","jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pflOKK-15Y","pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/posts\/4214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/users\/179014711"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/comments?post=4214"}],"version-history":[{"count":14,"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/posts\/4214\/revisions"}],"predecessor-version":[{"id":4351,"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/posts\/4214\/revisions\/4351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/media\/4265"}],"wp:attachment":[{"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/media?parent=4214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/categories?post=4214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/tags?post=4214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}