{"id":3509,"date":"2023-09-24T16:51:54","date_gmt":"2023-09-24T16:51:54","guid":{"rendered":"https:\/\/www.zonwizard.com\/blog\/?p=3509"},"modified":"2023-10-05T09:15:18","modified_gmt":"2023-10-05T09:15:18","slug":"solicitudes-reembolso-existencias-perdidas-de-amazon","status":"publish","type":"post","link":"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/","title":{"rendered":"Solicitudes Reembolso Existencias Perdidas de Amazon"},"content":{"rendered":"<p>La herramienta de Anal\u00edticas de ZonWizard monitorea constantemente tu inventario e <strong>identifica productos para los cuales tienes derecho a recibir un reembolso<\/strong>. Esto ocurre en casos en los que Amazon ha perdido o da\u00f1ado tu mercanc\u00eda en los centros log\u00edsticos o en casos en los que la devoluci\u00f3n de un cliente nunca regres\u00f3 al almac\u00e9n.<\/p>\n<p>En este tutorial veremos c\u00f3mo, gracias a ZonWizard, puedes abrir f\u00e1cil y r\u00e1pidamente casos en Seller Central, adjuntando toda la documentaci\u00f3n necesaria para obtener los reembolsos que te corresponden.<\/p>\n<p><!--more--><\/p>\n<h2>Resumen de productos faltantes<\/h2>\n<p>En la secci\u00f3n <a href=\"https:\/\/app.zonwizard.com\/analytics\/reconciliation\/\" target=\"_blank\" rel=\"noopener\">Anal\u00edticas &gt; Reembolsos<\/a>, puedes ver una lista de productos para los cuales se han identificado unidades faltantes que deben ser reembolsadas.<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3587\" data-permalink=\"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/screenshot-2023-10-05-alle-10-59-37\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-10.59.37.png?fit=1096%2C1070&amp;ssl=1\" data-orig-size=\"1096,1070\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Screenshot 2023-10-05 alle 10.59.37\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-10.59.37.png?fit=650%2C635&amp;ssl=1\" class=\"alignnone wp-image-3587 \" src=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-10.59.37.png?resize=440%2C430&#038;ssl=1\" alt=\"\" width=\"440\" height=\"430\" srcset=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-10.59.37.png?resize=300%2C293&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-10.59.37.png?resize=810%2C791&amp;ssl=1 810w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-10.59.37.png?resize=307%2C300&amp;ssl=1 307w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-10.59.37.png?resize=768%2C750&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-10.59.37.png?resize=1024%2C1000&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-10.59.37.png?w=1096&amp;ssl=1 1096w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/p>\n<p>La columna &#8220;Faltantes | Reclamadas&#8221; muestra las unidades faltantes encontradas hasta la fecha y las unidades pendientes de reembolso para las cuales ya se ha abierto un caso. Las unidades faltantes se dividen por tipo:<\/p>\n<ul>\n<li><strong>Perdidas<\/strong> (en la log\u00edstica de Amazon)<\/li>\n<li><strong>Da\u00f1adas<\/strong> (por la log\u00edstica de Amazon)<\/li>\n<li><strong>De entrada<\/strong> (de env\u00edos de entrada a los almacenes FBA)<\/li>\n<li><strong>No devueltas<\/strong> (por clientes que han recibido un reembolso)<\/li>\n<\/ul>\n<p>La columna &#8220;Reembolsable&#8221; proporciona una <strong>estimaci\u00f3n de referencia<\/strong> del monto que Amazon deber\u00eda reembolsar por todas las unidades faltantes. El monto se estima en funci\u00f3n del \u00faltimo precio de venta disponible o, alternativamente, del costo de compra del producto indicado por el usuario en la herramienta Profit.<\/p>\n<p>En la columna &#8220;Acciones&#8221;, se muestra en rojo el bot\u00f3n para iniciar el proceso de reclamaci\u00f3n o, si ya se ha abierto un caso, el bot\u00f3n para abrirlo en el registro de casos de Seller Central.<\/p>\n<p><span class=\"colour\"><span class=\"size\">\t\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\t\tvar gCaptchaSibWidget;\n                        var onloadSibCallbackInvisible = function () {\n\n                            var element = document.getElementsByClassName('sib-default-btn');\n                            var countInvisible = 0;\n                            var indexArray = [];\n                            jQuery('.sib-default-btn').each(function (index, el) {\n                                if ((jQuery(el).attr('id') == \"invisible\")) {\n                                    indexArray[countInvisible] = index;\n                                    countInvisible++\n                                }\n                            });\n\n                            jQuery('.invi-recaptcha').each(function (index, el) {\n                                grecaptcha.render(element[indexArray[index]], {\n                                    'sitekey': jQuery(el).attr('data-sitekey'),\n                                    'callback': sibVerifyCallback,\n                                });\n                            });\n                        };\n\t\t\t\t\t<\/script>\n\t\t\t\t\t                <script src=\"https:\/\/www.google.com\/recaptcha\/api.js?onload=onloadSibCallbackInvisible&render=explicit\" async defer><\/script>\n\t\t\t\t\n\t\t\t<form id=\"sib_signup_form_6\" method=\"post\" class=\"sib_signup_form\">\n\t\t\t\t<div class=\"sib_loader\" style=\"display:none;\"><img data-recalc-dims=\"1\"\n\t\t\t\t\t\t\tsrc=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-includes\/images\/spinner.gif?w=650&#038;ssl=1\" alt=\"loader\"><\/div>\n\t\t\t\t<input type=\"hidden\" name=\"sib_form_action\" value=\"subscribe_form_submit\">\n\t\t\t\t<input type=\"hidden\" name=\"sib_form_id\" value=\"6\">\n                <input type=\"hidden\" name=\"sib_form_alert_notice\" value=\"Rellene los campos obligatorios\">\n                <input type=\"hidden\" name=\"sib_form_invalid_email_notice\" value=\"Su direcci\u00f3n de correo electr\u00f3nico parece no ser v\u00e1lida\">\n                <input type=\"hidden\" name=\"sib_security\" value=\"479c0a34c2\">\n\t\t\t\t<div class=\"sib_signup_box_inside_6\">\n\t\t\t\t\t<div style=\"\/*display:none*\/\" class=\"sib_msg_disp\">\n\t\t\t\t\t<\/div>\n                                            <div id=\"sib_captcha_invisible\" class=\"invi-recaptcha\" data-sitekey=\"6LcMN7gUAAAAAD-_qJb0nFTTZqsPjxY-UjJ2aAoa\"><\/div>\n                    \t\t\t\t\t<div class=\"form-container\">\r\n        <h3 class=\"form-title\"><strong>Suscr\u00edbete al Bolet\u00edn<\/strong><\/h3>\r\n        <p>Art\u00edculos, minigu\u00edas y actualizaciones sobre el mundo de Amazon por parte de expertos en el campo.<\/p>\r\n        <div>\r\n            <div class=\"form-input\">\r\n                <input type=\"text\" class=\"sib-NOME-area\" name=\"NOME\" placeholder=\"Nombre\" required=\"required\">\r\n            <\/div>\r\n            <div class=\"form-input\">\r\n                <input type=\"email\" class=\"sib-email-area\" name=\"email\" placeholder=\"Correo Electr\u00f3nico\" required=\"required\">\r\n            <\/div>\r\n            <div class=\"checkbox-alignment\">\r\n                <input type=\"checkbox\" name=\"terms\" required=\"required\"> Acepto la <a class=\"text-white\" href=\"https:\/\/www.zonwizard.com\/es\/privacy\"><u>pol\u00edtica de privacidad<\/u><\/a>\r\n            <\/div>\r\n        <\/div>\r\n\r\n        <input type=\"text\" class=\"sib-LANGUAGE-area\" name=\"LANGUAGE\" value=\"es\">\r\n\r\n        <input type=\"submit\" id=\"invisible\" class=\"sib-default-btn\" value=\"Suscribirme al Bolet\u00edn\">\r\n    <\/div>\t\t\t\t<\/div>\n\t\t\t<\/form>\n\t\t\t<style>\n\t\t\t\tform#sib_signup_form_6 {background-color: #727cf5;padding: 30px;border-radius: 30px;margin: auto; -moz-box-sizing:border-box; -webkit-box-sizing: border-box; box-sizing: border-box; color:white; margin-bottom:20px } form#sib_signup_form_6 input[type=text],form#sib_signup_form_6 input[type=email], form#sib_signup_form_6 select { width: 100%; border: 1px solid #bbb; height: auto; margin: 5px 0 0 0; background-color:#e7e9fd;} form#sib_signup_form_6 .sib-default-btn { width:100%; margin: 5px 0; padding: 10px 12px; color:#727cf5; background-color: #fff; border: 2px solid #fff; font-size: 14px; font-weight:400; line-height: 1.4285; text-align: center; cursor: pointer; vertical-align: middle; -webkit-user-select:none; -moz-user-select:none; -ms-user-select:none; user-select:none; white-space: normal; border-radius: 500px; } form#sib_signup_form_6 .sib-default-btn:hover { background-color: #727cf5;color: #fff;border: 2px solid #fff;} form#sib_signup_form_6 p{ margin: 10px 0 0 0; } form#sib_signup_form_6 .sib-LANGUAGE-area{ display: none; } .form-input { width: 47%; margin-bottom: 10px; display:inline-block; } .text-white{color:white} .form-container { max-width: 400px; margin: auto; color: white; text-align: center } .form-title { margin-bottom: 0px; margin-top: 0px }form#sib_signup_form_6 p.sib-alert-message {\n    padding: 6px 12px;\n    margin-bottom: 20px;\n    border: 1px solid transparent;\n    border-radius: 4px;\n    -webkit-box-sizing: border-box;\n    -moz-box-sizing: border-box;\n    box-sizing: border-box;\n}\nform#sib_signup_form_6 p.sib-alert-message-error {\n    background-color: #f2dede;\n    border-color: #ebccd1;\n    color: #a94442;\n}\nform#sib_signup_form_6 p.sib-alert-message-success {\n    background-color: #dff0d8;\n    border-color: #d6e9c6;\n    color: #3c763d;\n}\nform#sib_signup_form_6 p.sib-alert-message-warning {\n    background-color: #fcf8e3;\n    border-color: #faebcc;\n    color: #8a6d3b;\n}\n\t\t\t<\/style>\n\t\t\t<\/span><\/span><\/p>\n<h3>Abrir una solicitud de reembolso<\/h3>\n<p>Al hacer clic en el bot\u00f3n &#8220;Reclamar&#8221;, comienzas el proceso en 3 pasos para abrir un caso.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3593\" data-permalink=\"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/screenshot-2023-10-05-alle-11-06-34\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.06.34.png?fit=988%2C872&amp;ssl=1\" data-orig-size=\"988,872\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Screenshot 2023-10-05 alle 11.06.34\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.06.34.png?fit=650%2C574&amp;ssl=1\" class=\"wp-image-3593 aligncenter\" src=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.06.34.png?resize=499%2C441&#038;ssl=1\" alt=\"\" width=\"499\" height=\"441\" srcset=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.06.34.png?resize=300%2C265&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.06.34.png?resize=810%2C715&amp;ssl=1 810w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.06.34.png?resize=340%2C300&amp;ssl=1 340w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.06.34.png?resize=768%2C678&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.06.34.png?w=988&amp;ssl=1 988w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><\/p>\n<p>En el primer paso, puedes descargar un <strong>informe Excel que contiene un resumen de las unidades faltantes y detalles de las razones<\/strong>. Recomendamos descargar estos documentos porque Amazon podr\u00eda requerirlos para la resoluci\u00f3n del caso.<\/p>\n<p>Una vez que hayas descargado los archivos, puedes proceder al siguiente paso haciendo clic en el bot\u00f3n &#8220;Siguiente&#8221;.<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3592\" data-permalink=\"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/screenshot-2023-10-05-alle-11-06-48\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.06.48.png?fit=992%2C1360&amp;ssl=1\" data-orig-size=\"992,1360\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Screenshot 2023-10-05 alle 11.06.48\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.06.48.png?fit=650%2C891&amp;ssl=1\" class=\"alignnone wp-image-3592 \" src=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.06.48.png?resize=499%2C684&#038;ssl=1\" alt=\"\" width=\"499\" height=\"684\" srcset=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.06.48.png?resize=219%2C300&amp;ssl=1 219w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.06.48.png?resize=810%2C1110&amp;ssl=1 810w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.06.48.png?resize=768%2C1053&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.06.48.png?resize=747%2C1024&amp;ssl=1 747w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.06.48.png?w=992&amp;ssl=1 992w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><\/p>\n<p>En el segundo paso, se proporciona la plantilla que se debe usar como descripci\u00f3n del problema al abrir el caso.<\/p>\n<p>Al usar el bot\u00f3n &#8220;Abrir caso en Seller Central&#8221;, se abre directamente la p\u00e1gina de ayuda al vendedor donde puedes pegar la descripci\u00f3n del problema. Amazon ofrece opciones de resoluci\u00f3n r\u00e1pida que var\u00edan seg\u00fan el tipo de productos faltantes.<\/p>\n<p>El procedimiento proporciona indicaciones sobre qu\u00e9 opciones seleccionar para llegar a la resoluci\u00f3n del caso lo m\u00e1s r\u00e1pido posible.<\/p>\n<p>Si se solicita contacto por correo electr\u00f3nico al final del proceso, es recomendable adjuntar el documento de Excel previamente descargado.<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2624\" data-permalink=\"https:\/\/www.zonwizard.com\/blog\/refund-claims-for-lost-and-damaged-fba-inventory\/refund-4\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/04\/refund-4.png?fit=1325%2C842&amp;ssl=1\" data-orig-size=\"1325,842\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"refund 4\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/04\/refund-4.png?fit=650%2C413&amp;ssl=1\" class=\"alignnone wp-image-2624 \" src=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/04\/refund-4.png?resize=650%2C414&#038;ssl=1\" alt=\"\" width=\"650\" height=\"414\" srcset=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/04\/refund-4.png?resize=300%2C191&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/04\/refund-4.png?resize=810%2C515&amp;ssl=1 810w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/04\/refund-4.png?resize=1140%2C724&amp;ssl=1 1140w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/04\/refund-4.png?resize=472%2C300&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/04\/refund-4.png?resize=768%2C488&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/04\/refund-4.png?resize=1024%2C651&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/04\/refund-4.png?resize=1200%2C763&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/04\/refund-4.png?w=1325&amp;ssl=1 1325w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>Una vez completados los pasos para abrir el caso en Seller Central, puedes proceder con el \u00faltimo paso en ZonWizard.<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3591\" data-permalink=\"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/screenshot-2023-10-05-alle-11-07-00\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.07.00.png?fit=986%2C858&amp;ssl=1\" data-orig-size=\"986,858\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Screenshot 2023-10-05 alle 11.07.00\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.07.00.png?fit=650%2C566&amp;ssl=1\" class=\"alignnone wp-image-3591 \" src=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.07.00.png?resize=499%2C434&#038;ssl=1\" alt=\"\" width=\"499\" height=\"434\" srcset=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.07.00.png?resize=300%2C261&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.07.00.png?resize=810%2C705&amp;ssl=1 810w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.07.00.png?resize=345%2C300&amp;ssl=1 345w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.07.00.png?resize=768%2C668&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.07.00.png?w=986&amp;ssl=1 986w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><\/p>\n<p>Debes copiar de Seller Central y pegar en ZonWizard el n\u00famero identificativo que Amazon acaba de asignar al caso que se acaba de abrir y hacer clic en el bot\u00f3n &#8220;Guardar&#8221;. Esto permite que el software haga un seguimiento de los pr\u00f3ximos reembolsos que Amazon emitir\u00e1 y que supervise el progreso del caso.<\/p>\n<h2>Seguimiento de casos<\/h2>\n<p>Una vez que se hayan realizado las solicitudes de reembolso, los casos aparecer\u00e1n en una lista como se muestra en esta captura de pantalla:<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3601\" data-permalink=\"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/screenshot-2023-10-05-alle-11-00-26\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.00.26.png?fit=1718%2C636&amp;ssl=1\" data-orig-size=\"1718,636\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Screenshot 2023-10-05 alle 11.00.26\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.00.26.png?fit=650%2C241&amp;ssl=1\" class=\"alignnone wp-image-3601 \" src=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.00.26.png?resize=650%2C240&#038;ssl=1\" alt=\"\" width=\"650\" height=\"240\" srcset=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.00.26.png?resize=300%2C111&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.00.26.png?resize=810%2C300&amp;ssl=1 810w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.00.26.png?resize=1140%2C422&amp;ssl=1 1140w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.00.26.png?resize=700%2C259&amp;ssl=1 700w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.00.26.png?resize=768%2C284&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.00.26.png?resize=1024%2C379&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.00.26.png?resize=1536%2C569&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.00.26.png?resize=1200%2C444&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.00.26.png?w=1718&amp;ssl=1 1718w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/09\/Screenshot-2023-10-05-alle-11.00.26.png?w=1300&amp;ssl=1 1300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>Desde aqu\u00ed, puedes monitorear f\u00e1cilmente el estado de las solicitudes:<\/p>\n<ul>\n<li>en amarillo: caso abierto pendiente de reembolso<\/li>\n<li>en verde: caso cerrado y reembolsado<\/li>\n<li>en gris: caso cerrado sin reembolso<\/li>\n<\/ul>\n<p>Al hacer clic en el &#8220;ID del caso&#8221;, ser\u00e1s redirigido directamente al registro de casos en Seller Central, mientras que al hacer clic en el icono junto a los productos individuales, puedes descargar los documentos que se adjuntaron en el momento de la solicitud.<\/p>\n<p>El monto reembolsado para el caso individual se muestra en la columna &#8220;Reembolsado&#8221;, mientras que el monto total reembolsado para todos los casos abiertos a trav\u00e9s de ZonWizard se muestra en la parte superior de la tabla.<\/p>\n<p><span class=\"colour\"><span class=\"size\"><a href=\"https:\/\/www.zonwizard.com\/es\/features?utm_source=blog&amp;utm_medium=banner&amp;utm_campaign=learnmoreprofit_es#profit\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3044 size-large\" src=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/08\/Banner-ZW-Profit-Tool-ES-1.png?resize=650%2C159&#038;ssl=1\" alt=\"Herramienta de beneficios ZonWizard.Toma el control total de tu negocio en Amazon. Ver\u00e1s claramente las ganancias reales, los m\u00e1rgenes, el ROI, los pedidos y los costos de cada producto. Programa autom\u00e1ticamente solicitudes de rese\u00f1as para tus pedidos.\" width=\"650\" height=\"159\" srcset=\"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/08\/Banner-ZW-Profit-Tool-ES-1.png?resize=1024%2C250&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/08\/Banner-ZW-Profit-Tool-ES-1.png?resize=810%2C198&amp;ssl=1 810w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/08\/Banner-ZW-Profit-Tool-ES-1.png?resize=1140%2C278&amp;ssl=1 1140w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/08\/Banner-ZW-Profit-Tool-ES-1.png?resize=700%2C171&amp;ssl=1 700w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/08\/Banner-ZW-Profit-Tool-ES-1.png?resize=300%2C73&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/08\/Banner-ZW-Profit-Tool-ES-1.png?resize=768%2C187&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/08\/Banner-ZW-Profit-Tool-ES-1.png?resize=1536%2C375&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/08\/Banner-ZW-Profit-Tool-ES-1.png?resize=1200%2C293&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/08\/Banner-ZW-Profit-Tool-ES-1.png?w=1640&amp;ssl=1 1640w, https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2023\/08\/Banner-ZW-Profit-Tool-ES-1.png?w=1300&amp;ssl=1 1300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/a><\/span><\/span><\/p>\n<h3>Eliminar un caso<\/h3>\n<p>En la columna &#8220;Acciones&#8221;, al hacer clic en el icono de la papelera, puedes eliminar un caso que se haya abierto por error o de manera incorrecta. Esta acci\u00f3n devuelve a ZonWizard a su estado anterior como si el caso nunca se hubiera creado.<\/p>\n<h3>Cerrar un caso<\/h3>\n<p>El software monitorea los reembolsos recibidos despu\u00e9s de la apertura del caso y si se obtiene un reembolso por todos los productos dentro de la solicitud, el sistema cerrar\u00e1 autom\u00e1ticamente el caso.<\/p>\n<p>Alternativamente, el usuario puede decidir, evaluando las respuestas obtenidas del soporte de Amazon, cerrar un caso antes de recibir un reembolso por todas las unidades solicitadas. Esta acci\u00f3n se realiza haciendo clic en la &#8220;X&#8221; y de esta manera, el caso se cierra y todos los productos en la solicitud se consideran no faltantes.<\/p>\n<blockquote><p><strong>Solo se puede abrir un caso por producto por tipo (perdido, da\u00f1ado, no devuelto). Para abrir un nuevo caso del mismo tipo para un producto, el caso previamente abierto debe haber sido cerrado o eliminado.<\/strong><\/p><\/blockquote>\n<h2>Resumen<\/h2>\n<p>Si has le\u00eddo este tutorial, te habr\u00e1s dado cuenta de que a trav\u00e9s de la herramienta de &#8220;Solicitudes de Reembolso&#8221; de ZonWizard puedes:<\/p>\n<ul>\n<li>ver un <strong>resumen de productos perdidos, da\u00f1ados y devueltos que no han regresado a Amazon<\/strong> en un panel simple e intuitivo, sin necesidad de cruzar informes de inventario<\/li>\n<li><strong>solicitar reembolsos a Amazon a trav\u00e9s de un asistente<\/strong>, con plantillas y documentos precompletados para adjuntar al caso<\/li>\n<li><strong>seguir el estado de los casos abiertos<\/strong> (solicitado-reembolsado-cerrado), con un seguimiento completo de los montos reembolsados y las unidades devueltas.<\/li>\n<\/ul>\n<p>Esperamos que este tutorial te haya ayudado a comprender el potencial de esta herramienta que permite recuperar el valor del inventario faltante de manera sistem\u00e1tica.<\/p>\n<p>Si ya eres un usuario de ZonWizard, encontrar\u00e1s esta funci\u00f3n en la secci\u00f3n <a href=\"https:\/\/app.zonwizard.com\/analytics\/reconciliation\/\" target=\"_blank\" rel=\"noopener\">Anal\u00edticas &gt; Reembolsos<\/a>.<\/p>\n<p>O puedes registrarte en nuestro servicio y disfrutar de 14 d\u00edas de prueba gratuita.<\/p>\n<div class=\"cta-container\">\r\n<h3 class=\"cta-h2\"><strong>Prueba la Herramienta de An\u00e1lisis Gratis<\/strong><\/h3>\r\n<p class=\"\">Impulsa tu negocio en Amazon al siguiente nivel. Reduce los costos de inventario con sugerencias de niveles de stock \u00f3ptimos, descubre los h\u00e1bitos de compra de tus clientes y genera estrategias avanzadas de venta. Si a\u00fan no est\u00e1s familiarizado con la Herramienta de An\u00e1lisis de ZonWizard, descubre c\u00f3mo puede ayudarte a optimizar y hacer crecer tu negocio.<\/p>\r\n<p class=\"\"><a class=\"button cta-button\" href=\"https:\/\/www.zonwizard.com\/es\/features?utm_source=blog&amp;utm_medium=CTA&amp;utm_campaign=ProfitTool_LearnMore#analytics\">M\u00e1s informaci\u00f3n<\/a><\/p>\r\n\r\n<\/div>\n<p>Gracias por leer nuestro Tutorial de Solicitudes de Reembolso.<\/p>\n<p>Encuentra m\u00e1s gu\u00edas similares a esta en la secci\u00f3n <a href=\"https:\/\/www.zonwizard.com\/blog\/it\/category\/tutorial\/\">Tutorial<\/a> de nuestro Blog<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a1Buena ventas!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La herramienta de Anal\u00edticas de ZonWizard monitorea constantemente tu inventario e identifica productos para los cuales tienes derecho a recibir un reembolso. Esto ocurre en casos en los que Amazon ha perdido o da\u00f1ado tu mercanc\u00eda en los centros log\u00edsticos o en casos en los que la devoluci\u00f3n de un cliente nunca regres\u00f3 al almac\u00e9n.&hellip;<\/p>\n","protected":false},"author":179014709,"featured_media":220,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_crdt_document":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[308],"tags":[],"class_list":["post-3509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tutorial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Solicitudes Reembolso Existencias Perdidas de Amazon - ZonWizard<\/title>\n<meta name=\"description\" content=\"Con ZonWizard puede abrir casos en Seller Central de forma r\u00e1pida y sencilla y obtener reembolsos por sus productos perdidos o da\u00f1ados.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solicitudes Reembolso Existencias Perdidas de Amazon - ZonWizard\" \/>\n<meta property=\"og:description\" content=\"Con ZonWizard puede abrir casos en Seller Central de forma r\u00e1pida y sencilla y obtener reembolsos por sus productos perdidos o da\u00f1ados.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/\" \/>\n<meta property=\"og:site_name\" content=\"ZonWizard\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-24T16:51:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-05T09:15:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zonwizard.com\/blog\/wp-content\/uploads\/2021\/09\/Settings.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"454\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"emily080254\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"emily080254\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/es\\\/solicitudes-reembolso-existencias-perdidas-de-amazon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/es\\\/solicitudes-reembolso-existencias-perdidas-de-amazon\\\/\"},\"author\":{\"name\":\"emily080254\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#\\\/schema\\\/person\\\/fb44051881e03c699f5c5a54c6bd45f2\"},\"headline\":\"Solicitudes Reembolso Existencias Perdidas de Amazon\",\"datePublished\":\"2023-09-24T16:51:54+00:00\",\"dateModified\":\"2023-10-05T09:15:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/es\\\/solicitudes-reembolso-existencias-perdidas-de-amazon\\\/\"},\"wordCount\":1063,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/es\\\/solicitudes-reembolso-existencias-perdidas-de-amazon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.zonwizard.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Settings.jpg?fit=1200%2C454&ssl=1\",\"articleSection\":[\"Tutorial\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/es\\\/solicitudes-reembolso-existencias-perdidas-de-amazon\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/es\\\/solicitudes-reembolso-existencias-perdidas-de-amazon\\\/\",\"url\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/es\\\/solicitudes-reembolso-existencias-perdidas-de-amazon\\\/\",\"name\":\"Solicitudes Reembolso Existencias Perdidas de Amazon - ZonWizard\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/es\\\/solicitudes-reembolso-existencias-perdidas-de-amazon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/es\\\/solicitudes-reembolso-existencias-perdidas-de-amazon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.zonwizard.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Settings.jpg?fit=1200%2C454&ssl=1\",\"datePublished\":\"2023-09-24T16:51:54+00:00\",\"dateModified\":\"2023-10-05T09:15:18+00:00\",\"description\":\"Con ZonWizard puede abrir casos en Seller Central de forma r\u00e1pida y sencilla y obtener reembolsos por sus productos perdidos o da\u00f1ados.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/es\\\/solicitudes-reembolso-existencias-perdidas-de-amazon\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/es\\\/solicitudes-reembolso-existencias-perdidas-de-amazon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/es\\\/solicitudes-reembolso-existencias-perdidas-de-amazon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.zonwizard.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Settings.jpg?fit=1200%2C454&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.zonwizard.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Settings.jpg?fit=1200%2C454&ssl=1\",\"width\":1200,\"height\":454},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/es\\\/solicitudes-reembolso-existencias-perdidas-de-amazon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solicitudes Reembolso Existencias Perdidas de Amazon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/\",\"name\":\"ZonWizard\",\"description\":\"Academy\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#organization\",\"name\":\"ZonWizard\",\"url\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.zonwizard.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/ZW_logo_L2TCB-1.png?fit=1400%2C248&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.zonwizard.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/ZW_logo_L2TCB-1.png?fit=1400%2C248&ssl=1\",\"width\":1400,\"height\":248,\"caption\":\"ZonWizard\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCvVlC0KBpllkAWBl63VPeBA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/#\\\/schema\\\/person\\\/fb44051881e03c699f5c5a54c6bd45f2\",\"name\":\"emily080254\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dfa4e37a178a531c38e22f284a8f4273d2c99616b7cfa5704cab0f1897b2f5f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dfa4e37a178a531c38e22f284a8f4273d2c99616b7cfa5704cab0f1897b2f5f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dfa4e37a178a531c38e22f284a8f4273d2c99616b7cfa5704cab0f1897b2f5f6?s=96&d=mm&r=g\",\"caption\":\"emily080254\"},\"url\":\"https:\\\/\\\/www.zonwizard.com\\\/blog\\\/author\\\/emily080254\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solicitudes Reembolso Existencias Perdidas de Amazon - ZonWizard","description":"Con ZonWizard puede abrir casos en Seller Central de forma r\u00e1pida y sencilla y obtener reembolsos por sus productos perdidos o da\u00f1ados.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/","og_locale":"en_US","og_type":"article","og_title":"Solicitudes Reembolso Existencias Perdidas de Amazon - ZonWizard","og_description":"Con ZonWizard puede abrir casos en Seller Central de forma r\u00e1pida y sencilla y obtener reembolsos por sus productos perdidos o da\u00f1ados.","og_url":"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/","og_site_name":"ZonWizard","article_publisher":"https:\/\/www.facebook.com\/","article_published_time":"2023-09-24T16:51:54+00:00","article_modified_time":"2023-10-05T09:15:18+00:00","og_image":[{"width":1200,"height":454,"url":"https:\/\/www.zonwizard.com\/blog\/wp-content\/uploads\/2021\/09\/Settings.jpg","type":"image\/jpeg"}],"author":"emily080254","twitter_card":"summary_large_image","twitter_misc":{"Written by":"emily080254","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/#article","isPartOf":{"@id":"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/"},"author":{"name":"emily080254","@id":"https:\/\/www.zonwizard.com\/blog\/#\/schema\/person\/fb44051881e03c699f5c5a54c6bd45f2"},"headline":"Solicitudes Reembolso Existencias Perdidas de Amazon","datePublished":"2023-09-24T16:51:54+00:00","dateModified":"2023-10-05T09:15:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/"},"wordCount":1063,"commentCount":0,"publisher":{"@id":"https:\/\/www.zonwizard.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2021\/09\/Settings.jpg?fit=1200%2C454&ssl=1","articleSection":["Tutorial"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/","url":"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/","name":"Solicitudes Reembolso Existencias Perdidas de Amazon - ZonWizard","isPartOf":{"@id":"https:\/\/www.zonwizard.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/#primaryimage"},"image":{"@id":"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2021\/09\/Settings.jpg?fit=1200%2C454&ssl=1","datePublished":"2023-09-24T16:51:54+00:00","dateModified":"2023-10-05T09:15:18+00:00","description":"Con ZonWizard puede abrir casos en Seller Central de forma r\u00e1pida y sencilla y obtener reembolsos por sus productos perdidos o da\u00f1ados.","breadcrumb":{"@id":"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/#primaryimage","url":"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2021\/09\/Settings.jpg?fit=1200%2C454&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2021\/09\/Settings.jpg?fit=1200%2C454&ssl=1","width":1200,"height":454},{"@type":"BreadcrumbList","@id":"https:\/\/www.zonwizard.com\/blog\/es\/solicitudes-reembolso-existencias-perdidas-de-amazon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zonwizard.com\/blog\/it\/"},{"@type":"ListItem","position":2,"name":"Solicitudes Reembolso Existencias Perdidas de Amazon"}]},{"@type":"WebSite","@id":"https:\/\/www.zonwizard.com\/blog\/#website","url":"https:\/\/www.zonwizard.com\/blog\/","name":"ZonWizard","description":"Academy","publisher":{"@id":"https:\/\/www.zonwizard.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zonwizard.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.zonwizard.com\/blog\/#organization","name":"ZonWizard","url":"https:\/\/www.zonwizard.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zonwizard.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2021\/09\/ZW_logo_L2TCB-1.png?fit=1400%2C248&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2021\/09\/ZW_logo_L2TCB-1.png?fit=1400%2C248&ssl=1","width":1400,"height":248,"caption":"ZonWizard"},"image":{"@id":"https:\/\/www.zonwizard.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/","https:\/\/www.youtube.com\/channel\/UCvVlC0KBpllkAWBl63VPeBA"]},{"@type":"Person","@id":"https:\/\/www.zonwizard.com\/blog\/#\/schema\/person\/fb44051881e03c699f5c5a54c6bd45f2","name":"emily080254","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/dfa4e37a178a531c38e22f284a8f4273d2c99616b7cfa5704cab0f1897b2f5f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dfa4e37a178a531c38e22f284a8f4273d2c99616b7cfa5704cab0f1897b2f5f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dfa4e37a178a531c38e22f284a8f4273d2c99616b7cfa5704cab0f1897b2f5f6?s=96&d=mm&r=g","caption":"emily080254"},"url":"https:\/\/www.zonwizard.com\/blog\/author\/emily080254\/"}]}},"lang":"es","translations":{"es":3509,"en":2577,"it":2557,"de":3501,"fr":3513},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.zonwizard.com\/blog\/wp-content\/uploads\/2021\/09\/Settings.jpg?fit=1200%2C454&ssl=1","jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pflOKK-UB","pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/posts\/3509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/users\/179014709"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/comments?post=3509"}],"version-history":[{"count":6,"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/posts\/3509\/revisions"}],"predecessor-version":[{"id":3603,"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/posts\/3509\/revisions\/3603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/media\/220"}],"wp:attachment":[{"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/media?parent=3509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/categories?post=3509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zonwizard.com\/blog\/wp-json\/wp\/v2\/tags?post=3509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}